{"id":92,"count":1,"description":"","link":"https:\/\/www.filmfestivaldelgarda.com\/ffg\/tag\/bresciatoday\/","name":"BresciaToday","slug":"bresciatoday","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.filmfestivaldelgarda.com\/ffg\/wp-json\/wp\/v2\/tags\/92"}],"collection":[{"href":"https:\/\/www.filmfestivaldelgarda.com\/ffg\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.filmfestivaldelgarda.com\/ffg\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.filmfestivaldelgarda.com\/ffg\/wp-json\/wp\/v2\/posts?tags=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}